{"id":27,"date":"2016-05-28T09:14:57","date_gmt":"2016-05-28T09:14:57","guid":{"rendered":"http:\/\/www.daenzer-dachundholz.ch\/html\/?page_id=27"},"modified":"2017-04-24T16:24:32","modified_gmt":"2017-04-24T16:24:32","slug":"bedachungen","status":"publish","type":"page","link":"https:\/\/www.daenzer-dachundholz.ch\/html\/angebot\/bedachungen\/","title":{"rendered":"Bedachungen"},"content":{"rendered":"<div id=\"pl-27\"  class=\"panel-layout\" ><div id=\"pg-27-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-27-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-27-0-0-0\" class=\"so-panel widget widget_text panel-first-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><div align=\"center\">Wir sind Ihre Spezialisten rund ums Dach! Ob Steild\u00e4cher, Unterd\u00e4cher und Isolationsd\u00e4cher oder Reparatur- und Unterhaltsarbeiten wie Dachreinigungen und Servicearbeiten sowie Moos- und Algenbek\u00e4mpfung.<br \/>\n<a href=\"#Kontakt\">Wir sind f\u00fcr Sie da \u2013 rufen Sie uns an.<\/a><\/div>\n<\/div>\n\t\t<\/div><div id=\"panel-27-0-0-1\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"1\" >\t\t\t<div class=\"textwidget\"><div id=\"metaslider-id-344\" style=\"max-width: 750px; margin: 0 auto;\" class=\"ml-slider-3-103-0 metaslider metaslider-flex metaslider-344 ml-slider has-dots-nav ms-theme-default\" role=\"region\" aria-label=\"Neue Diashow\" data-height=\"500\" data-width=\"750\">\n    <div id=\"metaslider_container_344\">\n        <div id=\"metaslider_344\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-348 ms-image \" aria-roledescription=\"slide\" data-date=\"2017-04-24 09:46:53\" data-slide-type=\"image\"><a href=\"http:\/\/www.daenzer-dachundholz.ch\/html\/projekte\/dach-galerien\/\" target=\"_self\" aria-label=\"View Slide Details\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-content\/uploads\/2017\/04\/01_bedachungen-750x500.jpg\" height=\"500\" width=\"750\" alt=\"Fritz D\u00e4nzer  Boltigen - Bedachungen - Bild 1\" class=\"slider-344 slide-348 msDefaultImage\" title=\"Foto &amp; Link - Galerie Dach\" \/><\/a><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-349 ms-image \" aria-roledescription=\"slide\" data-date=\"2017-04-24 09:47:08\" data-slide-type=\"image\"><a href=\"http:\/\/www.daenzer-dachundholz.ch\/html\/projekte\/dach-galerien\/\" target=\"_self\" aria-label=\"View Slide Details\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-content\/uploads\/2017\/04\/01_bedachungen-2-750x500.jpg\" height=\"500\" width=\"750\" alt=\"Fritz D\u00e4nzer  Boltigen - Bedachungen - Bild 2\" class=\"slider-344 slide-349 msDefaultImage\" title=\"Foto &amp; Link - Galerie Dach\" \/><\/a><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-350 ms-image \" aria-roledescription=\"slide\" data-date=\"2017-04-24 09:47:14\" data-slide-type=\"image\"><a href=\"http:\/\/www.daenzer-dachundholz.ch\/html\/projekte\/dach-galerien\/\" target=\"_self\" aria-label=\"View Slide Details\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-content\/uploads\/2017\/12\/Bedachung-Fritz-Daenzer-Dach-und-Holz-750x500.jpg\" height=\"500\" width=\"750\" alt=\"Fritz D\u00e4nzer  Boltigen - Bedachungen - Bild 3\" class=\"slider-344 slide-350 msDefaultImage\" title=\"Foto &amp; Link - Galerie Dach\" \/><\/a><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-351 ms-image \" aria-roledescription=\"slide\" data-date=\"2017-04-24 09:47:14\" data-slide-type=\"image\"><a href=\"http:\/\/www.daenzer-dachundholz.ch\/html\/projekte\/dach-galerien\/\" target=\"_self\" aria-label=\"View Slide Details\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-content\/uploads\/2017\/04\/01_bedachungen-4-750x500.jpg\" height=\"500\" width=\"750\" alt=\"Fritz D\u00e4nzer  Boltigen - Bedachungen - Bild 4\" class=\"slider-344 slide-351 msDefaultImage\" title=\"Foto &amp; Link - Galerie Dach\" \/><\/a><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Wir sind Ihre Spezialisten rund ums Dach! Ob Steild\u00e4cher, Unterd\u00e4cher und Isolationsd\u00e4cher oder Reparatur- und Unterhaltsarbeiten wie Dachreinigungen<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":24,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/pages\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":23,"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"predecessor-version":[{"id":29,"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/pages\/27\/revisions\/29"}],"up":[{"embeddable":true,"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/pages\/24"}],"wp:attachment":[{"href":"https:\/\/www.daenzer-dachundholz.ch\/html\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}